{"id":1729,"date":"2019-03-24T19:12:45","date_gmt":"2019-03-24T18:12:45","guid":{"rendered":"https:\/\/www.cbmmarine.com\/catalogo\/sea-ray-spx-190\/"},"modified":"2019-04-16T19:37:26","modified_gmt":"2019-04-16T17:37:26","slug":"sea-ray-spx-190","status":"publish","type":"catalogo","link":"https:\/\/www.cbmmarine.com\/en\/catalogo\/sea-ray-spx-190\/","title":{"rendered":"Sea Ray SPX 190"},"content":{"rendered":"","protected":false},"featured_media":728,"template":"","gama":[14,19],"class_list":["post-1729","catalogo","type-catalogo","status-publish","has-post-thumbnail","hentry","gama-sea-ray","gama-spx-series"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cbmmarine.com\/en\/wp-json\/wp\/v2\/catalogo\/1729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cbmmarine.com\/en\/wp-json\/wp\/v2\/catalogo"}],"about":[{"href":"https:\/\/www.cbmmarine.com\/en\/wp-json\/wp\/v2\/types\/catalogo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cbmmarine.com\/en\/wp-json\/wp\/v2\/media\/728"}],"wp:attachment":[{"href":"https:\/\/www.cbmmarine.com\/en\/wp-json\/wp\/v2\/media?parent=1729"}],"wp:term":[{"taxonomy":"gama","embeddable":true,"href":"https:\/\/www.cbmmarine.com\/en\/wp-json\/wp\/v2\/gama?post=1729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}